{"id":4492,"date":"2019-11-28T11:13:32","date_gmt":"2019-11-28T14:13:32","guid":{"rendered":"http:\/\/patrusananias.com.br\/blog\/?p=4039"},"modified":"2022-11-03T10:55:38","modified_gmt":"2022-11-03T13:55:38","slug":"deputado-patrus-ananias-visita-hospital-e-escolas-em-barbacena","status":"publish","type":"post","link":"https:\/\/patrusananias.com.br\/blog\/deputado-patrus-ananias-visita-hospital-e-escolas-em-barbacena\/","title":{"rendered":"Deputado Patrus Ananias visita hospital e escolas em Barbacena"},"content":{"rendered":"<p>O deputado federal Patrus Ananias cumpre agenda de trabalho nesta sexta-feira (29\/11) em Barbacena, Zona da Mata. O parlamentar se encontra com a equipe de professores do Col\u00e9gio S\u00e3o Francisco de Assis \u00e0s 10 horas e ainda na parte da manh\u00e3 d\u00e1 palestra sobre Educa\u00e7\u00e3o e Cidadania aos estudantes do 6\u00ba ao 9\u00ba ano do Ensino Fundamental.<\/p>\n<p><a href=\"http:\/\/patrusananias.com.br\/blog\/wp-content\/uploads\/2019\/11\/S\u00c3O-FRANCISCO-DE-ASSIS.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-4041\" alt=\"S\u00c3O FRANCISCO DE ASSIS\" src=\"http:\/\/patrusananias.com.br\/blog\/wp-content\/uploads\/2019\/11\/S\u00c3O-FRANCISCO-DE-ASSIS.jpg\" width=\"800\" height=\"600\" \/><\/a><\/p>\n<p>Mantida pelas Irm\u00e3s de S\u00e3o Francisco da Provid\u00eancia de Deus, a institui\u00e7\u00e3o oferece 370 vagas gratuitamente no Ensino Fundamental I e II, al\u00e9m de abrigar 26 projetos sociais destinados \u00e0s crian\u00e7as em situa\u00e7\u00e3o de vulnerabilidade social de 25 bairros da periferia de Barbacena.<\/p>\n<p><a href=\"http:\/\/patrusananias.com.br\/blog\/wp-content\/uploads\/2019\/11\/Relato\u0301rio-Parcial-2-01.jpg\"><img decoding=\"async\" class=\"aligncenter size-large wp-image-4040\" alt=\"Relato\u0301rio Parcial 2-01\" src=\"http:\/\/patrusananias.com.br\/blog\/wp-content\/uploads\/2019\/11\/Relato\u0301rio-Parcial-2-01-1024x724.jpg\" width=\"584\" height=\"412\" \/><\/a><\/p>\n<p>O almo\u00e7o ser\u00e1 na Associa\u00e7\u00e3o Cultural Ponto de Partida, beneficiada em 2018 com emenda parlamentar do mandato, no valor de R$ 500 mil. Este recurso possibilitou que o grupo teatral encenasse os espet\u00e1culos \u201cOs Gnomos\u201d (infantil) e \u201cMineiramente\u201d (juvenil) para 4.800 alunos de 17 escolas p\u00fablicas de Barbacena que visitaram a Esta\u00e7\u00e3o durante o ano de 2019, al\u00e9m de ministrar o curso Gest\u00e3o e Produ\u00e7\u00e3o Cultural para 112 pessoas de 28 cidades e quatro estados. Outra realiza\u00e7\u00e3o foi o curso de Musicaliza\u00e7\u00e3o, que durante 6 meses, permitiu que 80 crian\u00e7as, entre 5 e 12 anos, desenvolvessem a sensibilidade musical.<\/p>\n<p>A agenda ser\u00e1 encerrada, \u00e0s 15 horas, com visita t\u00e9cnica ao Hospital Ibiapaba, do Centro Barbacenense de Assist\u00eancia M\u00e9dica (CEBAMS). A unidade hospitalar tamb\u00e9m recebeu recursos de emenda do deputado, no valor de R$ 300 mil, em 2017. Atualmente o hospital possui pronto atendimento, ambulat\u00f3rio de especialidades, interna\u00e7\u00e3o cl\u00ednica e cir\u00fargica e \u00e9 refer\u00eancia nos servi\u00e7os de Cardiologia e Oncologia da Regi\u00e3o Ampliada de Sa\u00fade Centro-Sul de Minas Gerais.<\/p>\n<p><b>\u00a0<\/b><\/p>\n<p><strong>Agenda <\/strong><\/p>\n<p><b><\/b><strong>10h30 &#8211; Palestra &#8211; Educa\u00e7\u00e3o e Cidadania para os alunos do 6\u00ba ao 9\u00ba ano<\/strong><\/p>\n<p>Rua Jos\u00e9 Luiz de Medeiros, s\/n\u00ba \u00a0&#8211; S\u00edtio do Atalho \/ Pr\u00e9dio Escola<br \/>\nBairro Jo\u00e3o Paulo II &#8211;<\/p>\n<p><strong>12h &#8211; Almo\u00e7o no Ponto de Partida <\/strong><\/p>\n<p>Rua Luiz Delben s\/n\u00ba<\/p>\n<p><b><\/b><strong>15h &#8211; Visita ao Hospital Ibiapaba<\/strong><\/p>\n<p>Centro Barbacenense de Assist\u00eancia M\u00e9dica e Social (CEBAMS)<\/p>\n<p>Rua Silva Jardim, 580<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado federal Patrus Ananias cumpre agenda de trabalho nesta sexta-feira (29\/11) em Barbacena, Zona da Mata. O parlamentar se encontra com a equipe de professores do Col\u00e9gio S\u00e3o Francisco de Assis \u00e0s 10 horas e ainda na parte da manh\u00e3 d\u00e1 palestra sobre Educa\u00e7\u00e3o e Cidadania aos estudantes do 6\u00ba ao 9\u00ba ano do &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/patrusananias.com.br\/blog\/deputado-patrus-ananias-visita-hospital-e-escolas-em-barbacena\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Deputado Patrus Ananias visita hospital e escolas em Barbacena&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"views":261,"_links":{"self":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts\/4492"}],"collection":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4492"}],"version-history":[{"count":1,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts\/4492\/revisions"}],"predecessor-version":[{"id":6789,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts\/4492\/revisions\/6789"}],"wp:attachment":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}