{"id":3641,"date":"2019-04-17T18:02:37","date_gmt":"2019-04-17T21:02:37","guid":{"rendered":"http:\/\/patrusananias.com.br\/blog\/?p=3641"},"modified":"2022-11-03T10:54:55","modified_gmt":"2022-11-03T13:54:55","slug":"dia-internacional-de-luta-pela-reforma-agraria","status":"publish","type":"post","link":"https:\/\/patrusananias.com.br\/blog\/dia-internacional-de-luta-pela-reforma-agraria\/","title":{"rendered":"Dia Internacional de Luta pela Reforma Agr\u00e1ria"},"content":{"rendered":"<p>Nada mais fundamental que destacar a import\u00e2ncia dos movimentos sociais neste Dia Internacional de Luta pela Reforma Agr\u00e1ria. A sess\u00e3o solene da qual participei nos d\u00e1 a oportunidade de prestar o devido respeito, mas tamb\u00e9m de fazer um alerta: que \u00e9 preciso proteger as entidades que protegem os mais pobres, que defendem as mulheres e homens do campo.<\/p>\n<p>Os direitos sociais n\u00e3o caem do c\u00e9u nem brotam da terra. Eles s\u00e3o conquistados. E n\u00f3s precisamos dos movimentos sociais para que essa conquista se d\u00ea de forma pac\u00edfica, mas tamb\u00e9m de maneira organizada, combativa e incisiva.<\/p>\n<p>N\u00e3o podemos permitir, como quer este governo, a criminaliza\u00e7\u00e3o dos movimentos sociais. Defender entidades como a Via Campesina e o MST \u00e9 defender o nosso povo brasileiro.<\/p>\n<div style=\"width: 400px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-3641-1\" width=\"400\" height=\"220\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/patrusananias.com.br\/blog\/wp-content\/uploads\/2019\/05\/58145036_654837698315131_4090643654346014720_n.mp4?_=1\" \/><a href=\"http:\/\/patrusananias.com.br\/blog\/wp-content\/uploads\/2019\/05\/58145036_654837698315131_4090643654346014720_n.mp4\">http:\/\/patrusananias.com.br\/blog\/wp-content\/uploads\/2019\/05\/58145036_654837698315131_4090643654346014720_n.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nada mais fundamental que destacar a import\u00e2ncia dos movimentos sociais neste Dia Internacional de Luta pela Reforma Agr\u00e1ria. A sess\u00e3o solene da qual participei nos d\u00e1 a oportunidade de prestar o devido respeito, mas tamb\u00e9m de fazer um alerta: que \u00e9 preciso proteger as entidades que protegem os mais pobres, que defendem as mulheres e &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/patrusananias.com.br\/blog\/dia-internacional-de-luta-pela-reforma-agraria\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Dia Internacional de Luta pela Reforma Agr\u00e1ria&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,18],"tags":[],"views":239,"_links":{"self":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts\/3641"}],"collection":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3641"}],"version-history":[{"count":1,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts\/3641\/revisions"}],"predecessor-version":[{"id":6820,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts\/3641\/revisions\/6820"}],"wp:attachment":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}