{"id":2256,"date":"2017-03-23T10:34:57","date_gmt":"2017-03-23T13:34:57","guid":{"rendered":"http:\/\/patrusananias.com.br\/blog\/?p=2256"},"modified":"2022-11-03T10:42:49","modified_gmt":"2022-11-03T13:42:49","slug":"a-reforma-trabalhista-tenta-atropelar-pelo-menos-13-direitos-dos-trabalhadores","status":"publish","type":"post","link":"https:\/\/patrusananias.com.br\/blog\/a-reforma-trabalhista-tenta-atropelar-pelo-menos-13-direitos-dos-trabalhadores\/","title":{"rendered":"A &#8220;Reforma&#8221; Trabalhista tenta atropelar pelo menos 13 direitos dos trabalhadores"},"content":{"rendered":"<p>Depois da aprova\u00e7\u00e3o da terceiriza\u00e7\u00e3o ampla, a &#8220;reforma&#8221; trabalhista tenta anular de forma definitiva os direitos dos trabalhadores. Impedir que isso aconte\u00e7a \u00e9 o pr\u00f3ximo passo de nossa luta.<\/p>\n<p>Se aprovada essa &#8220;reforma&#8221;, pelo menos 13 direitos poder\u00e3o ser atropelados, retirando dos trabalhadores conquistas constitucionais. Algumas mudan\u00e7as que poder\u00e3o ocorrer s\u00e3o o aumento da dura\u00e7\u00e3o da jornada de trabalho, a redu\u00e7\u00e3o do intervalo de almo\u00e7o e o parcelamento do pagamento de f\u00e9rias.<\/p>\n<p>Qualquer empresa poder\u00e1 contratar trabalho tempor\u00e1rio por 120 dias (4 meses), transformando milh\u00f5es de empregos em \u201cbicos\u201d \u2013 sem direito, por exemplo, ao aviso pr\u00e9vio. Al\u00e9m disso, a reforma estimular\u00e1 a informalidade, pois as multas para empresas pela falta de registro de empregado ser\u00e3o muito menores do que os valores pela falta de registro formal do empregado (apenas R$ 6 mil, se for grande, e de s\u00f3 R$ 1 mil, se for pequena ou micro).<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/patrusananias.com.br\/blog\/wp-content\/uploads\/2017\/03\/Convite-ALMG-Reforma-Trabalhista-Marco-2017-texto.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-2257\" alt=\"Convite-ALMG-Reforma-Trabalhista-Marco-2017-texto\" src=\"http:\/\/patrusananias.com.br\/blog\/wp-content\/uploads\/2017\/03\/Convite-ALMG-Reforma-Trabalhista-Marco-2017-texto.png\" width=\"800\" height=\"550\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois da aprova\u00e7\u00e3o da terceiriza\u00e7\u00e3o ampla, a &#8220;reforma&#8221; trabalhista tenta anular de forma definitiva os direitos dos trabalhadores. Impedir que isso aconte\u00e7a \u00e9 o pr\u00f3ximo passo de nossa luta. Se aprovada essa &#8220;reforma&#8221;, pelo menos 13 direitos poder\u00e3o ser atropelados, retirando dos trabalhadores conquistas constitucionais. Algumas mudan\u00e7as que poder\u00e3o ocorrer s\u00e3o o aumento da dura\u00e7\u00e3o &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/patrusananias.com.br\/blog\/a-reforma-trabalhista-tenta-atropelar-pelo-menos-13-direitos-dos-trabalhadores\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;A &#8220;Reforma&#8221; Trabalhista tenta atropelar pelo menos 13 direitos dos trabalhadores&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,45],"tags":[],"views":274,"_links":{"self":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts\/2256"}],"collection":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2256"}],"version-history":[{"count":1,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts\/2256\/revisions"}],"predecessor-version":[{"id":6606,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts\/2256\/revisions\/6606"}],"wp:attachment":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}