{"id":1607,"date":"2016-07-13T23:25:32","date_gmt":"2016-07-14T02:25:32","guid":{"rendered":"http:\/\/patrusananias.com.br\/blog\/?p=1607"},"modified":"2022-11-03T10:56:30","modified_gmt":"2022-11-03T13:56:30","slug":"movimentos-sociais-do-campo-denunciam-golpes-de-ruralistas-em-cpi","status":"publish","type":"post","link":"https:\/\/patrusananias.com.br\/blog\/movimentos-sociais-do-campo-denunciam-golpes-de-ruralistas-em-cpi\/","title":{"rendered":"Movimentos sociais do campo denunciam golpes de ruralistas em CPI"},"content":{"rendered":"<p><a href=\"http:\/\/patrusananias.com.br\/blog\/wp-content\/uploads\/2016\/07\/ato-dos-indios.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-1608\" alt=\"ato dos indios\" src=\"http:\/\/patrusananias.com.br\/blog\/wp-content\/uploads\/2016\/07\/ato-dos-indios.jpg\" width=\"700\" height=\"398\" \/><\/a><\/p>\n<p>A Articula\u00e7\u00e3o dos Povos Ind\u00edgenas do Brasil, a Confedera\u00e7\u00e3o Nacional dos Trabalhadores na Agricultura, a Coordena\u00e7\u00e3o Nacional Quilombola, a Federa\u00e7\u00e3o dos Trabalhadores na Agricultura Familiar e o Movimento dos Trabalhadores Rurais Sem Terra (MST) divulgaram em Bras\u00edlia, nesta quarta-feira, 13, a \u201cCarta dos Movimentos Sociais do Campo contra os golpes da bancada ruralista no Congresso Nacional\u201d.<br \/>\nO documento acusa o comando da CPI Funai\/Incra, representativo da bancada ruralista, de praticar desmando e autoritarismo; e usar indevidamente as estruturas do Estado e a comiss\u00e3o para obter benef\u00edcios pr\u00f3prios e retirar direitos que estavam assegurados aos \u00edndios, aos quilombolas, aos agricultores familiares e aos que lutam pela reforma agr\u00e1ria.<br \/>\nOs movimentos denunciam que a maioria ruralista instalada na CPI concentra seus principais esfor\u00e7os em tentar desmoralizar e criminalizar membros dos movimentos sociais, estudiosos, trabalhadores rurais, ind\u00edgenas e quilombolas que lutam pelo direito a terra e ao territ\u00f3rio\u201d.<!--more--><br \/>\nA \u201cCarta dos Movimentos Sociais do Campo\u201d manifesta a esperan\u00e7a de que suas den\u00fancias, em \u00e2mbito nacional e internacional, despertem a solidariedade \u201cde todas as organiza\u00e7\u00f5es sociais e dos mais diferentes setores da sociedade que tamb\u00e9m lutam por direitos e justi\u00e7a\u201d, para construir uma forte rede de apoio e de press\u00e3o pelos direitos dos povos ind\u00edgenas, povos e comunidades tradicionais do Brasil (&#8230;).\u201d<br \/>\nA divulga\u00e7\u00e3o da Carta em ato no Sal\u00e3o Verde da C\u00e2mara foi antecedida, na v\u00e9spera, pela apresenta\u00e7\u00e3o \u00e0 Mesa Diretora de documento em que parlamentares de tr\u00eas partidos pedem a anula\u00e7\u00e3o de decis\u00f5es tomadas recentemente pela CPI Funai\/Incra. O documento lido em plen\u00e1rio pelo deputado Patrus Ananias levanta a suspeita de que o comando da CPI cometeu 12 infra\u00e7\u00f5es ao Regimento da C\u00e2mara.<br \/>\nAo ato de ontem compareceram, al\u00e9m de Patrus, o coordenador da bancada do PT na CPI da Funai\/Incra, deputado Nilto Tatto (PT-SP); o presidente da Comiss\u00e3o de Direitos Humanos e Minorias da C\u00e2mara, Padre Jo\u00e3o (MG), o coordenador do N\u00facleo Agr\u00e1rio do PT, Jo\u00e3o Daniel (SE), e os deputados petistas Adelmo Le\u00e3o (MG), Bohn Gass (RS), Erika Kokay (DF), Marcon (RS) e Valmir Assun\u00e7\u00e3o (BA).<\/p>\n<p>A \u00edntegra da Carta:<\/p>\n<p>Carta dos Movimentos Sociais do Campo contra os golpes da bancada ruralista no Congresso Nacional<br \/>\nN\u00f3s, organiza\u00e7\u00f5es e movimentos sociais abaixo assinados, que integram a articula\u00e7\u00e3o unit\u00e1ria dos povos do campo, da floresta e das \u00e1guas, perante os ataques orquestrados pela bancada ruralista no Congresso Nacional contra os nossos direitos, estamos por meio desta carta, denunciando os membros desse parlamento brasileiro que usam indevidamente as estruturas do Estado e o instrumento da Comiss\u00e3o Parlamentar de Inqu\u00e9rito (CPI) para obterem benef\u00edcios pr\u00f3prios e retirarem direitos inalien\u00e1veis a n\u00f3s assegurados.<br \/>\nEm outubro de 2015, por iniciativa de parlamentares vinculados aos interesses do agroneg\u00f3cio, foi criada uma Comiss\u00e3o Parlamentar de Inqu\u00e9rito \u2013 CPI, para supostamente investigar a atua\u00e7\u00e3o da Funda\u00e7\u00e3o Nacional do \u00cdndio (FUNAI) e do Instituto Nacional de Coloniza\u00e7\u00e3o e Reforma Agr\u00e1ria (INCRA) a respeito da demarca\u00e7\u00e3o das terras ind\u00edgenas e da titula\u00e7\u00e3o dos territ\u00f3rios dos remanescentes de quilombos, entre tantas outras quest\u00f5es de fato.<br \/>\nEsta den\u00fancia se embasa no fato de que a cria\u00e7\u00e3o e o funcionamento desta CPI negam todo e qualquer princ\u00edpio constitucional, legal, jur\u00eddico e normativo, n\u00e3o se amparando em fatos determinados e nem em justificativas de fundamento. Com uma participa\u00e7\u00e3o majorit\u00e1ria, os membros da bancada ruralista, utilizam-se de in\u00fameros expedientes para aprovarem ou rejeitarem apenas as mat\u00e9rias que atendem aos seus pr\u00f3prios interesses e constroem situa\u00e7\u00f5es que extrapolam, em muito, um papel regular que deveria ter uma CPI. Os parlamentares concentram os principais esfor\u00e7os da CPI para tentar desmoralizar e criminalizar membros dos movimentos sociais, estudiosos, trabalhadores rurais, ind\u00edgenas e quilombolas que lutam pelo direito a terra e ao territ\u00f3rio. Da mesma forma, atacam instrumentos, pol\u00edticas e as institui\u00e7\u00f5es p\u00fablicas que t\u00eam por finalidade jur\u00eddica atendar a estes povos.<br \/>\nA realidade de desmando e autoritarismo que ora denunciamos e que \u00e9 vivenciada nesta CPI, demonstra que a democracia representativa no Brasil ainda precisa avoluir para se consolidar. E para que isto ocorra, \u00e9 fundamental a realiza\u00e7\u00e3o de uma ampla reforma do sistema pol\u00edtico e, tamb\u00e9m, de pol\u00edticas estruturais que alterem a brutal concentra\u00e7\u00e3o da propriedade da terra e do poder, indo al\u00e9m do que foi poss\u00edvel com a retomada do processo democr\u00e1tico no Brasil, p\u00f3s golpe militar realizado em 1964 e que perdurou at\u00e9 1985. Aparentemente, nossa democracia seguia um curso de consolida\u00e7\u00e3o em nosso pa\u00eds, com os percal\u00e7os evidentes de sua jovialidade e de um sistema pol\u00edtico baseado na for\u00e7a do poder econ\u00f4mico.<br \/>\nCom a Constitui\u00e7\u00e3o Federal de 1988 e a inclus\u00e3o na Carta Magna de preceitos fundamentais da participa\u00e7\u00e3o popular, da busca pelo estado de bem estar e justi\u00e7a social e da afirmativa de garantias fundamentais \u00e0s minorias, afirma-se o Brasil como um Estado democr\u00e1tico de direito, apoiado em fundamentos, tais como a dignidade da pessoa humana (art.1\u00ba), em objetivos como a constru\u00e7\u00e3o de uma sociedade livre, justa e solid\u00e1ria, erradicando a fome e combatendo o preconceito (art. 3\u00ba) e dando a todos os cidad\u00e3os, a igualdade perante a lei (art.5\u00ba).<br \/>\nNo meio rural, mesmo n\u00e3o havendo um processo de amplia\u00e7\u00e3o da reforma agr\u00e1ria e da regulariza\u00e7\u00e3o fundi\u00e1ria de \u00e1reas ocupadas por povos e comunidades tradicionais, foi poss\u00edvel nos anos recentes, algumas melhorias significativas na qualidade de vida do povo, deflagrado, conjuntamente com pol\u00edticas de estrutura\u00e7\u00e3o econ\u00f4mica, de financiamento rural, de participa\u00e7\u00e3o social, afirmativo na busca da igualdade de ra\u00e7a, etnia, gera\u00e7\u00e3o e de g\u00eanero.<br \/>\nMas o sistema pol\u00edtico n\u00e3o foi alterado e a concentra\u00e7\u00e3o da riqueza e do poder n\u00e3o foi enfrentado a contento. No meio rural, continua o Brasil a ter uma das estruturas fundi\u00e1rias mais concentradas do mundo, com forte correla\u00e7\u00e3o entre o latif\u00fandio e o poder econ\u00f4mico e pol\u00edtico, onde impera a viol\u00eancia e o conflito fundi\u00e1rio como forma de intimida\u00e7\u00e3o social e de classe. Ainda n\u00e3o nos livramos da exist\u00eancia do trabalho escravo, h\u00e1 grupos e mil\u00edcias armadas bancadas pelos setores conservadores do meio rural que promovem o terror e a morte, consumimos mais agrot\u00f3xicos que qualquer outro pa\u00eds e caminhamos para ser os primeiros em produ\u00e7\u00e3o transg\u00eanica de gr\u00e3os.<br \/>\nO processo de demarca\u00e7\u00e3o de \u00e1reas ind\u00edgenas e quilombolas conduzido pelo Governo Federal, nos anos recentes, s\u00f3 ocorreu por conta de muita mobiliza\u00e7\u00e3o social, pois seguiam em ritmo de paralisia. Os or\u00e7amentos destinados para a FUNAI e para o INCRA sofreram fortes ajustes, reduzindo drasticamente a capacidade de a\u00e7\u00e3o. Na reforma agr\u00e1ria, o mesmo processo estava em curso, redu\u00e7\u00e3o no n\u00famero de fam\u00edlias assentadas e a invisibilidade do tema agr\u00e1rio na agenda do Governo Federal.<br \/>\nH\u00e1 uma casta ruralista que exerce seu poder por diferentes matizes. Com a bancada ruralista no Congresso Nacional, com mais de 200 representantes, exercem o poder pol\u00edtico. Com as vincula\u00e7\u00f5es ao empresariado conservador, refor\u00e7am os preceitos do capitalismo, pela explora\u00e7\u00e3o da m\u00e3o de obra e dos recursos naturais na sua exaust\u00e3o. E com forte vincula\u00e7\u00e3o econ\u00f4mica com as multinacionais do agroneg\u00f3cio, estabelecem a promiscua rela\u00e7\u00e3o patrimonialista sobre o Estado.<br \/>\nEsta casta atuou fortemente no processo golpista em curso no Brasil, que afasta momentaneamente, a Presidenta Dilma do cargo de Presidenta da Rep\u00fablica.<br \/>\nSeguindo prop\u00f3sitos semelhantes e complementares, a bancada ruralista se mobilizou para criar a Comiss\u00e3o Parlamentar de Inqu\u00e9rito destinada a investigar a atua\u00e7\u00e3o da FUNAI e INCRA na demarca\u00e7\u00e3o de terras ind\u00edgenas e de remanescentes de quilombos (CPI FUNAI\/INCRA), atropelando a Constitui\u00e7\u00e3o Federal e inobservando a exig\u00eancia do fato determinado, utilizando a CPI como instrumento de luta pol\u00edtica para acirrar os conflitos no campo.<br \/>\nA Constitui\u00e7\u00e3o Federal assegurou aos povos ind\u00edgenas o direito origin\u00e1rio e o uso exclusivo de suas terras tradicionais, \u00e0s suas cren\u00e7as, tradi\u00e7\u00f5es e l\u00edngua; \u00e0s comunidades quilombolas, a preserva\u00e7\u00e3o da cultura afro-brasileira e o reconhecimento de serem parte do patrim\u00f4nio cultural brasileiro; e a destina\u00e7\u00e3o para a reforma agr\u00e1ria dos im\u00f3veis rurais que n\u00e3o cumprem sua fun\u00e7\u00e3o social.<br \/>\nMesmo com estes direitos assegurados, os territ\u00f3rios ocupados pelos povos e comunidades tradicionais seguem sendo violados, invadidos e apropriados pelo agroneg\u00f3cio, pelos madeireiros e garimpeiros, que usurpam os recursos naturais e utilizam da viol\u00eancia costumeira para exercer o dom\u00ednio da terra.<br \/>\nS\u00e3o estes os direitos que est\u00e3o sendo amea\u00e7ados e que a bancada ruralista procura enfrentar por meio desta CPI. Al\u00e9m dos povos e comunidades tradicionais, a CPI procura constranger os servidores p\u00fablicos do INCRA e da FUNAI e destruir suas compet\u00eancias.<br \/>\nO governo interino e golpista de Michel Temer assevera este processo de opress\u00e3o e conflito, quando modifica em seu governo, a condu\u00e7\u00e3o pol\u00edtica dos \u00f3rg\u00e3os respons\u00e1veis pelas pol\u00edticas territoriais entregando-os aos partidos pol\u00edticos conservadores e com v\u00ednculos f\u00e1ticos com o agroneg\u00f3cio e com a bancada ruralista.<br \/>\nPor toda esta situa\u00e7\u00e3o aqui exposta, \u00e9 que os movimentos sociais rurais, que representam os assentados pela reforma agr\u00e1ria, os povos e as comunidades tradicionais, decidiram denunciar nacional e internacionalmente, os interesses dos ruralistas na condu\u00e7\u00e3o desta CPI, usando as estruturas do Estado, para retirar direitos sagrados.<br \/>\nEsperamos contar com a solidariedade de todas as organiza\u00e7\u00f5es sociais e dos mais diferentes setores da sociedade que tamb\u00e9m lutam por direitos e justi\u00e7a, para que possamos construir uma forte rede nacional e internacional de apoio \u00e0 causa dos povos ind\u00edgenas, povos e comunidades tradicionais do Brasil, pressionando as institui\u00e7\u00f5es para que fa\u00e7am prevalecer seus direitos a suas terras e territ\u00f3rios.<\/p>\n<p>PELO RESTABELECIMENTO DA ORDEM INSTITUCIONAL<br \/>\nPELA DEFESA DA DEMOCRACIA<br \/>\nFORA TEMER<\/p>\n<p>Bras\u00edlia, 12 de julho de 2016<\/p>\n<p>Articula\u00e7\u00e3o dos Povos Ind\u00edgenas do Brasil (APIB)<br \/>\nConfedera\u00e7\u00e3o Nacional dos Trabalhadores na Agricultura (CONTAG)<br \/>\nCoordena\u00e7\u00e3o Nacional Quilombola (CONAQ)<br \/>\nFedera\u00e7\u00e3o dos Trabalhadores na Agricultura Familiar (FETRAF)<br \/>\nMovimento dos Trabalhadores Rurais Sem Terra (MST)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Articula\u00e7\u00e3o dos Povos Ind\u00edgenas do Brasil, a Confedera\u00e7\u00e3o Nacional dos Trabalhadores na Agricultura, a Coordena\u00e7\u00e3o Nacional Quilombola, a Federa\u00e7\u00e3o dos Trabalhadores na Agricultura Familiar e o Movimento dos Trabalhadores Rurais Sem Terra (MST) divulgaram em Bras\u00edlia, nesta quarta-feira, 13, a \u201cCarta dos Movimentos Sociais do Campo contra os golpes da bancada ruralista no Congresso &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/patrusananias.com.br\/blog\/movimentos-sociais-do-campo-denunciam-golpes-de-ruralistas-em-cpi\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Movimentos sociais do campo denunciam golpes de ruralistas em CPI&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,3,6,7,19,41,16,20],"tags":[],"views":242,"_links":{"self":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts\/1607"}],"collection":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1607"}],"version-history":[{"count":1,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts\/1607\/revisions"}],"predecessor-version":[{"id":6986,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts\/1607\/revisions\/6986"}],"wp:attachment":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}