{"id":1281,"date":"2016-02-26T01:09:38","date_gmt":"2016-02-26T04:09:38","guid":{"rendered":"http:\/\/patrusananias.com.br\/blog\/?p=1281"},"modified":"2022-08-31T11:33:32","modified_gmt":"2022-08-31T14:33:32","slug":"objetivos-politicos-da-lava-jato-sao-claros","status":"publish","type":"post","link":"https:\/\/patrusananias.com.br\/blog\/objetivos-politicos-da-lava-jato-sao-claros\/","title":{"rendered":"&#8220;Objetivos pol\u00edticos da Lava Jato s\u00e3o claros&#8221;"},"content":{"rendered":"<p><a href=\"http:\/\/patrusananias.com.br\/blog\/wp-content\/uploads\/2016\/02\/patrus-capa-247.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-1283\" alt=\"patrus capa 247\" src=\"http:\/\/patrusananias.com.br\/blog\/wp-content\/uploads\/2016\/02\/patrus-capa-247.jpg\" width=\"300\" height=\"400\" \/><\/a><em><\/em><\/p>\n<p>Tereza Cruvinel<br \/>\nEm entrevista ao 247, o ministro do Desenvolvimento Agr\u00e1rio, Patrus Ananias, aponta os excessos e distor\u00e7\u00f5es da Opera\u00e7\u00e3o Lava Jato e fala de sua preocupa\u00e7\u00e3o com o conjunto de amea\u00e7as reais ao Estado Democr\u00e1tico de Direito que vem se ampliando.<\/p>\n<p>Em nome do combate \u00e0 corrup\u00e7\u00e3o, diz ele, a cruzada moralista, que tem objetivos pol\u00edticos claros, vem quebrando importantes garantias constitucionais, como o devido processo legal e a presun\u00e7\u00e3o da inoc\u00eancia.<!--more--><\/p>\n<p>Na pasta que ocupa desde o ano passado, ele persegue duas prioridades: uma, avan\u00e7ar na reforma agr\u00e1ria, aumentando o n\u00famero de fam\u00edlias assentadas. &#8220;Pessoas n\u00e3o foram feitas para viver debaixo de lona&#8221;, diz ele, reconhecendo que em seus governos, o PT n\u00e3o fez tudo o que precisava ser feita nesta \u00e1rea.<\/p>\n<p>Sua outra prioridade \u00e9 fortalecer a agricultura familiar, atrav\u00e9s do cr\u00e9dito, da assist\u00eancia t\u00e9cnica e de garantias de acesso ao mercado, inclusive atrav\u00e9s de compras e pre\u00e7os garantidos pelo governo.<\/p>\n<p>Hoje, o governo j\u00e1 \u00e9 obrigado a comprar da pequena agricultura pelo menos 30% dos alimentos que adquire. Patrus vem se batendo para ampliar esta percentual e tamb\u00e9m para recuperar as verbas do minist\u00e9rio, que este ano sofreram um corte de 50% no or\u00e7amento.<\/p>\n<p>A entrevista:<\/p>\n<p>247 \u2013 Como o senhor v\u00ea o atual est\u00e1gio da crise pol\u00edtica?<\/p>\n<p>Patrus Ananias \u2013 Tenho percebido em todas as pessoas, razo\u00e1veis e preocupadas com os destinos do pa\u00eds, uma grande apreens\u00e3o com o quadro pol\u00edtico. Todas se perguntam: onde vai dar tudo isso? At\u00e9 quando o pa\u00eds aguenta? Uma fonte de preocupa\u00e7\u00e3o \u00e9 com o crescente grau de intoler\u00e2ncia e sectarismo, que compromete o pluralismo, a conviv\u00eancia entre diferentes formas de pensar e diferentes posi\u00e7\u00f5es pol\u00edticas. Este \u00f3dio ao outro, esta divis\u00e3o que se aprofunda, tudo isso representa uma amea\u00e7a \u00e0 pr\u00f3pria democracia. Uma outra preocupa\u00e7\u00e3o \u00e9 com a forma, a meu ver equivocada, com que o problema da corrup\u00e7\u00e3o est\u00e1 sendo enfrentado. Os valores \u00e9ticos e republicanos precisam ser fortalecidos, mas a quest\u00e3o da corrup\u00e7\u00e3o deve precisa ser discutida e combatida com uma perspectiva mais ampla, hist\u00f3rica e cultural, revisitando o patrimonialismo que sempre marcou as rela\u00e7\u00f5es entre as elites e o Estado no Brasil. Um debate fulanizado e estas a\u00e7\u00f5es claramente direcionadas para um partido, como acontece agora em rela\u00e7\u00e3o ao PT pela Lava Jato, n\u00e3o resolver\u00e1 nada. Al\u00e9m de unir, precisamos atualizar nosso sistema pol\u00edtico, criando regras para moralizar o financiamento de campanhas e a rela\u00e7\u00e3o entre partidos, pol\u00edticos e empresas. Isso \u00e9 t\u00e3o ou mais importante que prender e condenar pessoas, mas n\u00e3o se est\u00e1 cuidando disso.<\/p>\n<p>247 \u2013 E por que, apesar destas limita\u00e7\u00f5es e dos excessos, a Lava Jato tornou-se intoc\u00e1vel?<\/p>\n<p>Patrus \u2013 A Lava Jato ningu\u00e9m questiona temendo ser acusado de coniv\u00eancia com a corrup\u00e7\u00e3o, e esta \u00e9 outra decorr\u00eancia do sectarismo e da intoler\u00e2ncia. Mas hoje est\u00e1 muito claro aonde querem chegar toda esta cruzada moralista.<\/p>\n<p>247 \u2013 Ao impeachment da presidente&#8230;<\/p>\n<p>Patrus \u2013 Existem os objetivos pol\u00edticos, que s\u00e3o muito claros, mas a condu\u00e7\u00e3o destes processos judiciais tem representado tamb\u00e9m uma amea\u00e7a \u00e0 democracia. Tem faltado respeito ao devido processo legal, ao direito ao contradit\u00f3rio, \u00e0 ampla defesa, \u00e0 presun\u00e7\u00e3o da inoc\u00eancia at\u00e9 prova em contr\u00e1rio. Tudo isso \u00e9 muito perigoso e n\u00e3o podemos aceitar passivamente. Aplica-se na esfera judicial e tamb\u00e9m na pol\u00edtica, como por exemplo ao caso do senador Delc\u00eddio Amaral, que n\u00e3o pode ser cassado pelo Senado enquanto n\u00e3o for julgado e estiverem esgotadas todas as possibilidades de recurso.<\/p>\n<p>247 \u2013 E existem as pris\u00f5es preventivas prolongadas para for\u00e7ar dela\u00e7\u00f5es premiadas, muito criticadas pela comunidade jur\u00eddica&#8230;<\/p>\n<p>Patrus \u2013 For\u00e7ar dela\u00e7\u00e3o premiada \u00e9 um procedimento muito question\u00e1vel, do ponto de vista moral e jur\u00eddico. Primeiro porque este n\u00e3o \u00e9 ainda um instrumento universalmente aceito pelo mundo jur\u00eddico, pelas as cortes e pelas constitui\u00e7\u00f5es. No Brasil, \u00e9 muito recente a lei que introduziu este mecanismo, j\u00e1 no primeiro governo Dilma. H\u00e1 algo de inquisitorial nesta pr\u00e1tica de subjugar o preso com a priva\u00e7\u00e3o da liberdade, sem que esteja condenado, mediante alega\u00e7\u00f5es como risco de fuga, para for\u00e7\u00e1-lo a delatar. Sem falar no fato de que alguns criminosos v\u00eam sendo premiados n\u00e3o s\u00f3 com a redu\u00e7\u00e3o de penas, mas com o direito de ficar com parte do patrim\u00f4nio acumulado durante o per\u00edodo em que cometeram il\u00edcitos. E ainda h\u00e1 os vazamentos seletivos, destinados a atingir alvos pol\u00edticos tamb\u00e9m selecionados. Do modo como as coisas est\u00e3o sendo conduzidas, um criminoso que faz dela\u00e7\u00e3o premiada acaba conquistando o papel de juiz. Conquista o direito de condenar pela simples men\u00e7\u00e3o ao nome de uma pessoa. A toda hora lemos e ouvimos dizer: &#8220;fulano de tal, mencionado na dela\u00e7\u00e3o premiada de beltrano&#8221;. Mencionado, est\u00e1 condenado pela opini\u00e3o p\u00fablica. Ent\u00e3o, a meu ver, s\u00e3o muitas as distor\u00e7\u00f5es neste modo de combater a corrup\u00e7\u00e3o e ministrar justi\u00e7a. Os democratas, e principalmente os que viveram e sofreram o autoritarismo, n\u00e3o podem se calar diante destas amea\u00e7as ao Estado Democr\u00e1tico de Direito.<\/p>\n<p>247 \u2013 E como tem sido dirigir uma pasta de alta sensibilidade social como a da Reforma e Desenvolvimento Agr\u00e1rio no meio de uma dupla crise como esta?<\/p>\n<p>Patrus \u2013 Desafiador, mas tamb\u00e9m estimulante, apesar das dificuldades, como a poda do or\u00e7amento deste ano em 50%. Agora estamos negociando com a \u00e1rea econ\u00f4mica para recompor, pelo menos parcialmente, os recursos da pasta. Precisamos deles para avan\u00e7ar nas duas frentes program\u00e1ticas quem s\u00e3o nossas prioridades.<\/p>\n<p>247 \u2013 Quais s\u00e3o elas?<\/p>\n<p>Patrus \u2013 Uma \u00e9 avan\u00e7ar na reforma agr\u00e1ria propriamente dita e a outra consolidar e implantar novas pol\u00edticas para o fortalecimento da agricultura familiar, algo muito importante em tempo de crise, afora os efeitos sociais permanentes. Al\u00e9m do mais, o cooperativismo \u00e9 algo que precisa ser fortalecido porque tem tamb\u00e9m uma dimens\u00e3o pol\u00edtico-filos\u00f3fica positiva. Reduz o individualismo, aumenta o sentimento de solidariedade e a pr\u00e1tica da ajuda m\u00fatua. Na agricultura familiar estamos tamb\u00e9m introduzindo valores agro-ecol\u00f3gicos, como a redu\u00e7\u00e3o do uso de transg\u00eanicos e de agrot\u00f3xicos.<\/p>\n<p>Mas para que esta agricultura das pequenas fam\u00edlias se consolide e contribua para o aumento da produ\u00e7\u00e3o de alimentos saud\u00e1veis, o governo precisa garantir mecanismos de acesso aos mercados, inclusive atrav\u00e9s da compra direta por \u00f3rg\u00e3os do governo. Estou muito empenhado nisso.<\/p>\n<p>247 \u2013 E a reforma agr\u00e1ria, vai mesmo deslanchar?<\/p>\n<p>Patrus \u2013 Admito que n\u00e3o fizemos, nos governos do PT, tudo o que era necess\u00e1rio nesta mat\u00e9ria, por um conjunto de raz\u00f5es. Em resumo, faltou \u00eanfase. Agora vamos tentar recuperar o tempo e ampliar o n\u00famero de fam\u00edlias assentadas, tirando pessoas dos acampamentos e contribuindo para fortalecer a pequena agricultura e a produ\u00e7\u00e3o de alimentos. Pessoas n\u00e3o foram feitas para viver debaixo de lona. Para acelerar este processo, criamos uma sala de situa\u00e7\u00e3o na qual buscamos identificar os acampamentos existentes e quantificar as fam\u00edlias e pessoas que demandam uma terra para viver e trabalhar.<\/p>\n<p>247 \u2013 Ainda existem muitas terras dispon\u00edveis para reforma agr\u00e1ria?<\/p>\n<p>Patrus \u2013 Estamos trabalhando intensamente na identifica\u00e7\u00e3o das terras que s\u00e3o pass\u00edveis de destina\u00e7\u00e3o \u00e0 reforma agr\u00e1ria, sejam elas publicas ou privadas, em condi\u00e7\u00f5es de serem desapropriadas. Em meu primeiro despacho com a presidenta Dilma, como ministro, ela me disse: &#8220;Patrus, n\u00e3o podemos ter favelas no campo&#8221;. Concordei e estou procurando responder ao desafio dela.<\/p>\n<p>247 \u2013 E a situa\u00e7\u00e3o fiscal tem permitido?<\/p>\n<p>Patrus \u2013 Apesar das dificuldades, no ano passado lan\u00e7amos o Plano Safra da Agricultura Familiar com aumento de 20% nos recursos. Foram alocados R$28,9 bilh\u00f5es a juros negativos. Depois lan\u00e7amos o PMAC, pelo qual pelo menos 30% das compras governamentais de alimentos devem vir da Agricultura Familiar. Estamos estimulando o pequeno agricultor a buscar os empr\u00e9stimos do Pronaf, apelando tamb\u00e9m ao Banco do Brasil e outros bancos para que facilitem o acesso, reduzindo a burocracia e o formalismo que amedrontam a gente mais simples do campo.<\/p>\n<p>247 \u2013 E o que tem sido feito para aumentar o conhecimento t\u00e9cnico destes pequenos produtores, geralmente ainda adeptos de praticas rudimentares?<\/p>\n<p>Patrus \u2013 Ah, sim, vamos investir muito na assist\u00eancia t\u00e9cnica. Estamos implantando a Anater \u2013 Ag\u00eancia Nacional de Assist\u00eancia T\u00e9cnica e Extens\u00e3o Rural, que se articular\u00e1 com as Ematers estaduais. Ela est\u00e1 juridicamente criada, mas ainda precisa de recursos para se organizar e estruturar. E complementarmente, precisamos garantir um pre\u00e7o m\u00ednimo ao pequeno agricultor. Ele planta na alta de pre\u00e7os e colhe na baixa. O governo precisa comprar estoques a um pre\u00e7o previamente garantido. Estocar alimentos, a meu ver, \u00e9 uma pol\u00edtica de soberania. \u00c9 preciso exportar, mas tamb\u00e9m ter reservas para o enfrentamento de alguma crise, seja de sazonalidade ou de qualquer origem. Montei uma boa equipe e com ela acredito que vamos colher bons resultados nestas duas frentes fundamentais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tereza Cruvinel Em entrevista ao 247, o ministro do Desenvolvimento Agr\u00e1rio, Patrus Ananias, aponta os excessos e distor\u00e7\u00f5es da Opera\u00e7\u00e3o Lava Jato e fala de sua preocupa\u00e7\u00e3o com o conjunto de amea\u00e7as reais ao Estado Democr\u00e1tico de Direito que vem se ampliando. Em nome do combate \u00e0 corrup\u00e7\u00e3o, diz ele, a cruzada moralista, que tem &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/patrusananias.com.br\/blog\/objetivos-politicos-da-lava-jato-sao-claros\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;&#8220;Objetivos pol\u00edticos da Lava Jato s\u00e3o claros&#8221;&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,5,16],"tags":[],"views":339,"_links":{"self":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts\/1281"}],"collection":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1281"}],"version-history":[{"count":1,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts\/1281\/revisions"}],"predecessor-version":[{"id":6524,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/posts\/1281\/revisions\/6524"}],"wp:attachment":[{"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patrusananias.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}